{"id":29,"count":24,"description":"Explorez les origines de la famille Kuhlman \u00e0 travers l'\u00e9pop\u00e9e militaire des trois fr\u00e8res Peter, Johan et Gerhardt durant la Guerre de Trente Ans. De la Garde du Roi Gustave II Adolphe \u00e0 l'anoblissement par la Reine Christine de Su\u00e8de, d\u00e9couvrez une v\u00e9ritable enqu\u00eate historique bas\u00e9e sur les archives militaires (Rullors) et les correspondances avec le Grand Chancelier Oxenstierna. Ce chapitre d\u00e9voile les exploits, les blessures et les alliances qui ont forg\u00e9 l'identit\u00e9 et le blason de la lign\u00e9e Kuhlman.","link":"https:\/\/kuhlmansaga.com\/sv\/category\/au-service-de-sa-majeste\/","name":"Au service de sa Majest\u00e9 (1600-1649)","slug":"au-service-de-sa-majeste","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}