{"id":45,"count":20,"description":"P\u00e9n\u00e9trez dans l'univers intellectuel et social de Johan Kuhlman (1738-1806). Cette cat\u00e9gorie explore son r\u00e9seau d'influence, de sa participation active \u00e0 la Franc-ma\u00e7onnerie su\u00e9doise du XVIIIe si\u00e8cle \u00e0 ses amiti\u00e9s \u00e9rudites, notamment avec Johan Henrik Lid\u00e9n. D\u00e9couvrez l'histoire de sa grande biblioth\u00e8que, ses voyages et les \u00e9changes \u00e9pistolaires qui t\u00e9moignent de l'effervescence culturelle de la Su\u00e8de Gustavienne et de l'esprit des Lumi\u00e8res au sein de la famille.","link":"https:\/\/kuhlmansaga.com\/sv\/category\/le-cercle-de-johan\/","name":"Johans krets","slug":"le-cercle-de-johan","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/categories\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kuhlmansaga.com\/sv\/wp-json\/wp\/v2\/posts?categories=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}